{"id":6604,"date":"2025-09-01T14:47:10","date_gmt":"2025-09-01T17:47:10","guid":{"rendered":"https:\/\/dspbiomedical.com.br\/?p=6604"},"modified":"2025-09-01T15:22:57","modified_gmt":"2025-09-01T18:22:57","slug":"reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01","status":"publish","type":"post","link":"https:\/\/dspbiomedical.com.br\/en\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/","title":{"rendered":"Reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas com implantes zigom\u00e1ticos: relato de caso cl\u00ednico 01"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas, onde a quantidade \u00f3ssea \u00e9 insuficiente tanto em altura quanto em largura, pode inviabilizar a instala\u00e7\u00e3o de implantes, caracterizando um dos maiores desafios da implantodontia. Uma das alternativas para esses casos \u00e9 a utiliza\u00e7\u00e3o de implantes zigom\u00e1ticos. Nesse artigo ser\u00e1 apresentada, atrav\u00e9s de dois relatos de casos cl\u00ednicos, uma forma de reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas por meio da utiliza\u00e7\u00e3o de implantes convencionais conjugados com a fixa\u00e7\u00e3o de implantes zigom\u00e1ticos. Nestes casos, uma pr\u00f3tese fixa parafusada sobre os implantes foi instalada tr\u00eas dias ap\u00f3s o procedimento cir\u00fargico, submetendo os implantes \u00e0 carga imediata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Palavras-chave: maxila, implantes convencionais, implantes zigom\u00e1ticos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Introdu\u00e7\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A reabilita\u00e7\u00e3o de pacientes parcial ou totalmente desdentados atrav\u00e9s de implantes tornou-se uma pr\u00e1tica comum na implantodontia, com resultados confi\u00e1veis ao longo do tempo e satisfa\u00e7\u00e3o dos pacientes<sup>1<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contudo, a insufici\u00eancia \u00f3ssea tanto em altura quanto em largura do rebordo alveolar devido \u00e0 reabsor\u00e7\u00e3o \u00f3ssea causada por extra\u00e7\u00f5es, traumas, infec\u00e7\u00f5es, pneumatiza\u00e7\u00e3o do seio maxilar, tumores, dentre outros<sup>2<\/sup>, permanece como um desafio frente a instala\u00e7\u00e3o de implantes osseointegr\u00e1veis para a ancoragem de pr\u00f3teses reabilitadoras<sup>3<\/sup>. Essa condi\u00e7\u00e3o de atrofia da maxila pode inviabilizar a instala\u00e7\u00e3o de implantes sem que antes seja realizado um procedimento reconstrutivo pr\u00e9vio. Nesse sentido, enxertos \u00f3sseos e implanta\u00e7\u00e3o de biomateriais t\u00eam sido utilizados como alternativa para a reabilita\u00e7\u00e3o na implantodontia. Entretanto, alguns eventos adversos como extenso tempo de tratamento, necessidade de cirurgias adicionais, possibilidade de complica\u00e7\u00f5es como hematomas, dor p\u00f3s-operat\u00f3ria, e desordens sensoriais associadas \u00e0 inviabilidade de utilizar a pr\u00f3tese existente durante o per\u00edodo p\u00f3s-cir\u00fargico levam a um menor percentual de aceita\u00e7\u00e3o desta op\u00e7\u00e3o de tratamento pelos pacientes<sup>4<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como uma alternativa cl\u00ednica, a instala\u00e7\u00e3o de implantes no osso zigom\u00e1tico para reabilita\u00e7\u00e3o de rebordos maxilares atr\u00f3ficos tem sido descrita com sucesso<sup>5<\/sup>. Esta t\u00e9cnica, introduzida por Branemark em 1988, \u00e9 respons\u00e1vel por reduzir o tempo de tratamento e a morbidade, devido ao fato de n\u00e3o requerer nenhum procedimento adjunto, podendo ser realizado em apenas um procedimento cir\u00fargico<sup>6, 7<\/sup>. Os implantes zigom\u00e1ticos t\u00eam seu comprimento ampliado (variando de 30 a 62,5 mm) e s\u00e3o instalados atrav\u00e9s do osso remanescente no rebordo maxilar, na regi\u00e3o do segundo pr\u00e9-molar ou primeiro molar e atravessa transversalmente o seio maxilar, penetrando no corpo do osso zigom\u00e1tico, regi\u00e3o de osso muito compacto<sup>8<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que essa t\u00e9cnica foi descrita, os implantes zigom\u00e1ticos t\u00eam sido utilizados na reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas quase sempre conectados com 2 a 4 implantes convencionais na regi\u00e3o anterior com altos \u00edndices de sucesso<sup>4, 9, 10<\/sup>. O objetivo deste artigo \u00e9 demonstrar, por meio de apresenta\u00e7\u00e3o de dois casos cl\u00ednicos, uma forma de reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas com a utiliza\u00e7\u00e3o de implantes zigom\u00e1ticos, seguindo a t\u00e9cnica exteriorizada<sup>11<\/sup>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Caso cl\u00ednico 1<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Paciente de 54 anos, do sexo masculino, apresentando boa sa\u00fade geral, relatou que procurou atendimento odontol\u00f3gico para realizar a manuten\u00e7\u00e3o regular de sua pr\u00f3tese maxilar implanto-suportada do tipo protocolo, instalada h\u00e1 oito anos. O profissional que o atendeu n\u00e3o solicitou nenhum tipo de exame radiogr\u00e1fico e, ao tentar remover a pr\u00f3tese do paciente, n\u00e3o conseguiu remover os parafusos de fixa\u00e7\u00e3o. Nesse processo, notou a presen\u00e7a de secre\u00e7\u00e3o purulenta, ent\u00e3o utilizou o f\u00f3rceps para remo\u00e7\u00e3o for\u00e7ada da pr\u00f3tese, o que terminou por fragmentar dois implantes do paciente de dif\u00edcil remo\u00e7\u00e3o, e fraturar um parafuso de fixa\u00e7\u00e3o. Um dos implantes foi avulsionado (Figura 1). Perante essa situa\u00e7\u00e3o, o profissional o informou que seus implantes eram irrepar\u00e1veis.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"554\" height=\"352\" src=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-paciente.png\" alt=\"\" class=\"wp-image-6605\" srcset=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-paciente.png 554w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-paciente-300x191.png 300w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-paciente-18x12.png 18w\" sizes=\"(max-width: 554px) 100vw, 554px\" \/><figcaption class=\"wp-element-caption\">Figura 1. Pr\u00f3tese utilizada pelo paciente que teve um de seus implantes fragmentado pela for\u00e7a exercida pelo f\u00f3rceps.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O paciente ent\u00e3o, procurou o consult\u00f3rio para uma nova avalia\u00e7\u00e3o. Foi realizado exame cl\u00ednico inicial e an\u00e1lise de exames radiogr\u00e1ficos (Raio X panor\u00e2mico e tomografia computadorizada). Durante a avalia\u00e7\u00e3o cl\u00ednica, houve extravasamento de secre\u00e7\u00e3o purulenta de cor amarelo citrino, e, atrav\u00e9s dos exames radiogr\u00e1ficos pode-se constatar que um dos implantes havia rompido a parede do seio maxilar, e ali se instalado, desencadeando a infec\u00e7\u00e3o (Figura 2). Atrav\u00e9s dos exames radiogr\u00e1ficos constatou-se tamb\u00e9m aus\u00eancia de quantidade \u00f3ssea suficiente para reabilita\u00e7\u00e3o do paciente por meio de novos implantes convencionais, exclusivamente (Figura 3). Al\u00e9m disso, verificou-se que o paciente possu\u00eda periodontite nos dentes remanescentes da mand\u00edbula, com mobilidade de grau 3.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"556\" height=\"315\" data-src=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/raio-x.png\" alt=\"\" class=\"wp-image-6606 lazyload\" data-srcset=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/raio-x.png 556w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/raio-x-300x170.png 300w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/raio-x-18x10.png 18w\" data-sizes=\"(max-width: 556px) 100vw, 556px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 556px; --smush-placeholder-aspect-ratio: 556\/315;\" \/><figcaption class=\"wp-element-caption\">Figura 2 &#8211; Raio-X<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"551\" height=\"261\" data-src=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/tomografia.png\" alt=\"\" class=\"wp-image-6607 lazyload\" data-srcset=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/tomografia.png 551w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/tomografia-300x142.png 300w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/tomografia-18x9.png 18w\" data-sizes=\"(max-width: 551px) 100vw, 551px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 551px; --smush-placeholder-aspect-ratio: 551\/261;\" \/><figcaption class=\"wp-element-caption\">Figura 3. Tomografia da regi\u00e3o posterior da maxila.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Frente a essa situa\u00e7\u00e3o, foi proposta a resolu\u00e7\u00e3o do caso com a utiliza\u00e7\u00e3o de implantes convencionais e zigom\u00e1ticos com a possibilidade de submeter esses implantes \u00e0 carga imediata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes da realiza\u00e7\u00e3o do procedimento cir\u00fargico, foram realizados procedimentos prot\u00e9ticos registrando as rela\u00e7\u00f5es maxilo mandibulares com a dimens\u00e3o vertical de oclus\u00e3o, utilizando planos de cera (Figura 4) para a confec\u00e7\u00e3o de um guia multifuncional. Para a confec\u00e7\u00e3o deste guia, foi realizada uma nova montagem dos dentes em cera, com a verifica\u00e7\u00e3o da correta est\u00e9tica, fon\u00e9tica, oclus\u00e3o, corredor bucal. Essa montagem duplicada, em resina incolor, \u00e9 a guia multifuncional.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"550\" height=\"293\" data-src=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/condicoees-iniciais.png\" alt=\"\" class=\"wp-image-6608 lazyload\" data-srcset=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/condicoees-iniciais.png 550w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/condicoees-iniciais-300x160.png 300w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/condicoees-iniciais-18x10.png 18w\" data-sizes=\"(max-width: 550px) 100vw, 550px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 550px; --smush-placeholder-aspect-ratio: 550\/293;\" \/><figcaption class=\"wp-element-caption\">Figura 4. Condi\u00e7\u00f5es iniciais do paciente. Registro das rela\u00e7\u00f5es maxilo-mandibulares.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Foram requisitados exames de sangue complementares (hemograma completo, tempo de coagula\u00e7\u00e3o, tempo de sangramento, glicemia em jejum), e avalia\u00e7\u00e3o cardiol\u00f3gica para determinar o risco cir\u00fargico do paciente antes da cirurgia, que foi realizado em ambiente ambulatorial, sob seda\u00e7\u00e3o com m\u00e9dico anestesiologista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante o procedimento cir\u00fargico, inicialmente realizou-se infiltra\u00e7\u00e3o anest\u00e9sica com vasoconstritor por toda a regi\u00e3o vestibular da maxila e palato visando reduzir o sangramento. A incis\u00e3o foi realizada na crista do rebordo maxilar com duas incis\u00f5es verticais relaxantes na regi\u00e3o de segundos molares. Logo ap\u00f3s, um retalho mucoperiostal foi rebatido expondo toda a regi\u00e3o onde foram instalados os implantes. Toda a extens\u00e3o da maxila foi exposta at\u00e9 a abertura piriforme, pilares caninos, zigom\u00e1tico e todo processo alveolar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a visualiza\u00e7\u00e3o do rebordo maxilar, inicialmente, foi instalado um implante convencional na regi\u00e3o anterior com a orienta\u00e7\u00e3o dada pela guia multifuncional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mantivemos o implante instalado no t\u00faber do lado esquerdo. O fragmento de parafuso de fixa\u00e7\u00e3o foi removido atrav\u00e9s de desgaste com uso de brocas. Foi necess\u00e1rio o uso de retificador de roscas no implante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para a remo\u00e7\u00e3o do implante na cavidade sinusal foi realizada uma pequena abertura na cavidade do seio maxilar para afastar a membrana sinusal, tentando manter sua integridade, e conseguimos pin\u00e7ar o implante para remov\u00ea-lo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e3o, seguiu-se a instala\u00e7\u00e3o de dois implantes zigom\u00e1ticos DSP Biomedical 40 mm e 45 mm (Campo Largo, PR) do lado direito da maxila. Para instala\u00e7\u00e3o dos implantes zigom\u00e1ticos utilizou-se a T\u00e9cnica Exteriorizada de Miglioran\u00e7a<sup>11<\/sup>, possibilitando que a sequ\u00eancia de fresagem seja totalmente vis\u00edvel. Nessa t\u00e9cnica, as sinusopatias n\u00e3o ocorrem, pois as fixa\u00e7\u00f5es zigom\u00e1ticas s\u00e3o instaladas externamente ao seio maxilar, e a aus\u00eancia de antrotomia impede que haja infec\u00e7\u00e3o do seio maxilar e que haja invagina\u00e7\u00e3o de tecidos moles para o interior deste (Figuras 5 e 6). Ao penetrar a broca pela vertente palatina do rebordo devido a severa atrofia do remanescente \u00f3sseo na maxila, a mesma se rompeu, caracterizando a T\u00e9cnica de Miglioran\u00e7a modificada<sup>12<\/sup>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"551\" height=\"339\" data-src=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/retalho.png\" alt=\"\" class=\"wp-image-6609 lazyload\" data-srcset=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/retalho.png 551w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/retalho-300x185.png 300w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/retalho-18x12.png 18w\" data-sizes=\"(max-width: 551px) 100vw, 551px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 551px; --smush-placeholder-aspect-ratio: 551\/339;\" \/><figcaption class=\"wp-element-caption\">Figura 5. Retalho mucoperiostal<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"552\" height=\"427\" data-src=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/implantes-zigomaticos.png\" alt=\"\" class=\"wp-image-6610 lazyload\" data-srcset=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/implantes-zigomaticos.png 552w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/implantes-zigomaticos-300x232.png 300w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/implantes-zigomaticos-16x12.png 16w\" data-sizes=\"(max-width: 552px) 100vw, 552px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 552px; --smush-placeholder-aspect-ratio: 552\/427;\" \/><figcaption class=\"wp-element-caption\">Figura 6. Implantes zigom\u00e1ticos instalados do lado direito.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Todos os implantes obtiveram boa estabilidade inicial (acima de 45 N\/cm), o que permitiu a submiss\u00e3o dos mesmos \u00e0 carga imediata, por isso \u00e9 realizada a instala\u00e7\u00e3o dos intermedi\u00e1rios prot\u00e9ticos com torque de 20N\/cm no ato cir\u00fargico. Com os pilares prot\u00e9ticos instalados, foi realizada a sutura com fio reabsorv\u00edvel, sempre atentando para a completa coapta\u00e7\u00e3o dos bordos do retalho a fim de evitar a entrada de material de moldagem durante os procedimentos prot\u00e9ticos (Figura 7).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s o procedimento cir\u00fargico, iniciou-se os procedimentos prot\u00e9ticos de moldagem de transfer\u00eancia dos implantes, da tomada das rela\u00e7\u00f5es maxilo-mandibulares e da posi\u00e7\u00e3o dos tecidos moles peri-implantes, com o aux\u00edlio da guia multifuncional. Logo ap\u00f3s, foi dado in\u00edcio aos procedimentos laboratoriais, com a confec\u00e7\u00e3o de uma infraestrutura met\u00e1lica unindo os implantes e a montagem dos dentes em cera sobre a mesma infraestrutura. Foi ent\u00e3o realizada a prova dos dentes em cera na boca do paciente, para verifica\u00e7\u00e3o da est\u00e9tica, fon\u00e9tica e oclus\u00e3o. Tamb\u00e9m foi realizada a verifica\u00e7\u00e3o do assentamento passivo da infraestrutura sobre os intermedi\u00e1rios prot\u00e9ticos.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"553\" height=\"316\" data-src=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/sutura.png\" alt=\"\" class=\"wp-image-6611 lazyload\" data-srcset=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/sutura.png 553w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/sutura-300x171.png 300w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/sutura-18x10.png 18w\" data-sizes=\"(max-width: 553px) 100vw, 553px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 553px; --smush-placeholder-aspect-ratio: 553\/316;\" \/><figcaption class=\"wp-element-caption\">Figura 7. Sutura com fio reabsorv\u00edvel.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Com os dentes em posi\u00e7\u00e3o correta e a infraestrutura passiva, foi realizada a acriliza\u00e7\u00e3o da pr\u00f3tese. Findado os procedimentos laboratoriais, a pr\u00f3tese definitiva foi instalada tr\u00eas dias ap\u00f3s o procedimento cir\u00fargico, onde foram realizados os primeiros ajustes oclusais necess\u00e1rios e orienta\u00e7\u00f5es quanto \u00e0 higieniza\u00e7\u00e3o da pr\u00f3tese. Nessa etapa tamb\u00e9m foi instalada e ajustada uma placa oclusal miorrelaxante, protegendo os implantes de qualquer h\u00e1bito parafuncional por parte do paciente (Figura 8 -10).<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"550\" height=\"339\" data-src=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-instalada.png\" alt=\"\" class=\"wp-image-6613 lazyload\" data-srcset=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-instalada.png 550w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-instalada-300x185.png 300w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-instalada-18x12.png 18w\" data-sizes=\"(max-width: 550px) 100vw, 550px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 550px; --smush-placeholder-aspect-ratio: 550\/339;\" \/><figcaption class=\"wp-element-caption\">Figura 8. Pr\u00f3teses instaladas<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"548\" height=\"386\" data-src=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-maxilar-instalada.png\" alt=\"\" class=\"wp-image-6615 lazyload\" data-srcset=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-maxilar-instalada.png 548w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-maxilar-instalada-300x211.png 300w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-maxilar-instalada-18x12.png 18w\" data-sizes=\"(max-width: 548px) 100vw, 548px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 548px; --smush-placeholder-aspect-ratio: 548\/386;\" \/><figcaption class=\"wp-element-caption\">Figura 9. Pr\u00f3tese maxilar instalada<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"552\" height=\"395\" data-src=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/raio-x-panoramico.png\" alt=\"\" class=\"wp-image-6617 lazyload\" data-srcset=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/raio-x-panoramico.png 552w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/raio-x-panoramico-300x215.png 300w, https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/raio-x-panoramico-18x12.png 18w\" data-sizes=\"(max-width: 552px) 100vw, 552px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 552px; --smush-placeholder-aspect-ratio: 552\/395;\" \/><figcaption class=\"wp-element-caption\">Figura 10. Raio X panor\u00e2mico final do caso<\/figcaption><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Caso cl\u00ednico desenvolvido por Rosenvaldo Moreira J\u00fanior<sup>1<\/sup>, Tain\u00e1 Carvalho Guerreiro<sup>2<\/sup><\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>A reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas, onde a quantidade \u00f3ssea \u00e9 insuficiente tanto em altura quanto em largura, pode inviabilizar a instala\u00e7\u00e3o de implantes, caracterizando um dos maiores desafios da implantodontia. Uma das alternativas para esses casos \u00e9 a utiliza\u00e7\u00e3o de implantes zigom\u00e1ticos. Nesse artigo ser\u00e1 apresentada, atrav\u00e9s de dois relatos de casos cl\u00ednicos, uma forma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6613,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-6604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-implantes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas com implantes zigom\u00e1ticos: relato de caso cl\u00ednico 01 - DSP Biomedical<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dspbiomedical.com.br\/en\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas com implantes zigom\u00e1ticos: relato de caso cl\u00ednico 01 - DSP Biomedical\" \/>\n<meta property=\"og:description\" content=\"A reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas, onde a quantidade \u00f3ssea \u00e9 insuficiente tanto em altura quanto em largura, pode inviabilizar a instala\u00e7\u00e3o de implantes, caracterizando um dos maiores desafios da implantodontia. Uma das alternativas para esses casos \u00e9 a utiliza\u00e7\u00e3o de implantes zigom\u00e1ticos. Nesse artigo ser\u00e1 apresentada, atrav\u00e9s de dois relatos de casos cl\u00ednicos, uma forma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dspbiomedical.com.br\/en\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/\" \/>\n<meta property=\"og:site_name\" content=\"DSP Biomedical\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-01T17:47:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-01T18:22:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-instalada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"339\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\\\/\"},\"author\":{\"name\":\"Eduardo\",\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/#\\\/schema\\\/person\\\/eac3a650c27be27d0b71cf600d547117\"},\"headline\":\"Reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas com implantes zigom\u00e1ticos: relato de caso cl\u00ednico 01\",\"datePublished\":\"2025-09-01T17:47:10+00:00\",\"dateModified\":\"2025-09-01T18:22:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\\\/\"},\"wordCount\":1614,\"publisher\":{\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dspbiomedical.com.br\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/protese-instalada.png\",\"articleSection\":[\"Implantes\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\\\/\",\"url\":\"https:\\\/\\\/dspbiomedical.com.br\\\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\\\/\",\"name\":\"Reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas com implantes zigom\u00e1ticos: relato de caso cl\u00ednico 01 - DSP Biomedical\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dspbiomedical.com.br\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/protese-instalada.png\",\"datePublished\":\"2025-09-01T17:47:10+00:00\",\"dateModified\":\"2025-09-01T18:22:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dspbiomedical.com.br\\\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dspbiomedical.com.br\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/protese-instalada.png\",\"contentUrl\":\"https:\\\/\\\/dspbiomedical.com.br\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/protese-instalada.png\",\"width\":550,\"height\":339},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/dspbiomedical.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas com implantes zigom\u00e1ticos: relato de caso cl\u00ednico 01\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/#website\",\"url\":\"https:\\\/\\\/dspbiomedical.com.br\\\/\",\"name\":\"DSP Biomedical\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dspbiomedical.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/#organization\",\"name\":\"DSP Biomedical\",\"url\":\"https:\\\/\\\/dspbiomedical.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dspbiomedical.com.br\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-logo_site_topo.png.webp\",\"contentUrl\":\"https:\\\/\\\/dspbiomedical.com.br\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-logo_site_topo.png.webp\",\"width\":117,\"height\":64,\"caption\":\"DSP Biomedical\"},\"image\":{\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dspbiomedical.com.br\\\/#\\\/schema\\\/person\\\/eac3a650c27be27d0b71cf600d547117\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a412530e13e894582db0843f9e211507e4b27e44e3eef44adbc9c526ca7a866e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a412530e13e894582db0843f9e211507e4b27e44e3eef44adbc9c526ca7a866e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a412530e13e894582db0843f9e211507e4b27e44e3eef44adbc9c526ca7a866e?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\\\/\\\/dspbiomedical.com.br\\\/en\\\/author\\\/dspbiomedical\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas com implantes zigom\u00e1ticos: relato de caso cl\u00ednico 01 - DSP Biomedical","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dspbiomedical.com.br\/en\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/","og_locale":"en_US","og_type":"article","og_title":"Reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas com implantes zigom\u00e1ticos: relato de caso cl\u00ednico 01 - DSP Biomedical","og_description":"A reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas, onde a quantidade \u00f3ssea \u00e9 insuficiente tanto em altura quanto em largura, pode inviabilizar a instala\u00e7\u00e3o de implantes, caracterizando um dos maiores desafios da implantodontia. Uma das alternativas para esses casos \u00e9 a utiliza\u00e7\u00e3o de implantes zigom\u00e1ticos. Nesse artigo ser\u00e1 apresentada, atrav\u00e9s de dois relatos de casos cl\u00ednicos, uma forma [&hellip;]","og_url":"https:\/\/dspbiomedical.com.br\/en\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/","og_site_name":"DSP Biomedical","article_published_time":"2025-09-01T17:47:10+00:00","article_modified_time":"2025-09-01T18:22:57+00:00","og_image":[{"width":550,"height":339,"url":"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-instalada.png","type":"image\/png"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eduardo","Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dspbiomedical.com.br\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/#article","isPartOf":{"@id":"https:\/\/dspbiomedical.com.br\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/"},"author":{"name":"Eduardo","@id":"https:\/\/dspbiomedical.com.br\/#\/schema\/person\/eac3a650c27be27d0b71cf600d547117"},"headline":"Reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas com implantes zigom\u00e1ticos: relato de caso cl\u00ednico 01","datePublished":"2025-09-01T17:47:10+00:00","dateModified":"2025-09-01T18:22:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dspbiomedical.com.br\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/"},"wordCount":1614,"publisher":{"@id":"https:\/\/dspbiomedical.com.br\/#organization"},"image":{"@id":"https:\/\/dspbiomedical.com.br\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/#primaryimage"},"thumbnailUrl":"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-instalada.png","articleSection":["Implantes"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dspbiomedical.com.br\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/","url":"https:\/\/dspbiomedical.com.br\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/","name":"Reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas com implantes zigom\u00e1ticos: relato de caso cl\u00ednico 01 - DSP Biomedical","isPartOf":{"@id":"https:\/\/dspbiomedical.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dspbiomedical.com.br\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/#primaryimage"},"image":{"@id":"https:\/\/dspbiomedical.com.br\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/#primaryimage"},"thumbnailUrl":"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-instalada.png","datePublished":"2025-09-01T17:47:10+00:00","dateModified":"2025-09-01T18:22:57+00:00","breadcrumb":{"@id":"https:\/\/dspbiomedical.com.br\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dspbiomedical.com.br\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dspbiomedical.com.br\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/#primaryimage","url":"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-instalada.png","contentUrl":"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2025\/09\/protese-instalada.png","width":550,"height":339},{"@type":"BreadcrumbList","@id":"https:\/\/dspbiomedical.com.br\/reabilitacao-de-maxilas-atroficas-com-implantes-zigomaticos-relato-caso-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/dspbiomedical.com.br\/"},{"@type":"ListItem","position":2,"name":"Reabilita\u00e7\u00e3o de maxilas atr\u00f3ficas com implantes zigom\u00e1ticos: relato de caso cl\u00ednico 01"}]},{"@type":"WebSite","@id":"https:\/\/dspbiomedical.com.br\/#website","url":"https:\/\/dspbiomedical.com.br\/","name":"DSP Biomedical","description":"","publisher":{"@id":"https:\/\/dspbiomedical.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dspbiomedical.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dspbiomedical.com.br\/#organization","name":"DSP Biomedical","url":"https:\/\/dspbiomedical.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dspbiomedical.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2024\/03\/cropped-logo_site_topo.png.webp","contentUrl":"https:\/\/dspbiomedical.com.br\/wp-content\/uploads\/2024\/03\/cropped-logo_site_topo.png.webp","width":117,"height":64,"caption":"DSP Biomedical"},"image":{"@id":"https:\/\/dspbiomedical.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dspbiomedical.com.br\/#\/schema\/person\/eac3a650c27be27d0b71cf600d547117","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a412530e13e894582db0843f9e211507e4b27e44e3eef44adbc9c526ca7a866e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a412530e13e894582db0843f9e211507e4b27e44e3eef44adbc9c526ca7a866e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a412530e13e894582db0843f9e211507e4b27e44e3eef44adbc9c526ca7a866e?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/dspbiomedical.com.br\/en\/author\/dspbiomedical\/"}]}},"_links":{"self":[{"href":"https:\/\/dspbiomedical.com.br\/en\/wp-json\/wp\/v2\/posts\/6604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dspbiomedical.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dspbiomedical.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dspbiomedical.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dspbiomedical.com.br\/en\/wp-json\/wp\/v2\/comments?post=6604"}],"version-history":[{"count":0,"href":"https:\/\/dspbiomedical.com.br\/en\/wp-json\/wp\/v2\/posts\/6604\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dspbiomedical.com.br\/en\/wp-json\/wp\/v2\/media\/6613"}],"wp:attachment":[{"href":"https:\/\/dspbiomedical.com.br\/en\/wp-json\/wp\/v2\/media?parent=6604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dspbiomedical.com.br\/en\/wp-json\/wp\/v2\/categories?post=6604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dspbiomedical.com.br\/en\/wp-json\/wp\/v2\/tags?post=6604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}